{"id":6617,"date":"2023-02-07T10:55:21","date_gmt":"2023-02-07T09:55:21","guid":{"rendered":"https:\/\/www.explora-sicilia.com\/privacy-policy\/"},"modified":"2024-01-25T16:02:45","modified_gmt":"2024-01-25T15:02:45","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\n<a class=\"iubenda-white no-brand iubenda-embed iub-body-embed\" title=\"Privacy Policy\" href=\"\/\/www.iubenda.com\/privacy-policy\/35280966\">Privacy Policy<\/a> <script type=\"text\/javascript\">(function (w,d) {var loader = function () {var s = d.createElement(\"script\"), tag = d.getElementsByTagName(\"script\")[0]; s.src=\"\/\/cdn.iubenda.com\/iubenda.js\"; tag.parentNode.insertBefore(s,tag);}; if(w.addEventListener){w.addEventListener(\"load\", loader, false);}else if(w.attachEvent){w.attachEvent(\"onload\", loader);}else{w.onload = loader;}})(window, document);<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Privacy Policy<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":29,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6617","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Explora Sicilia Natura &amp; Sport<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Explora Sicilia Natura &amp; Sport\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Explora Sicilia Natura &amp; Sport\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-25T15:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage1334.cdn-immedia.net\/wp-content\/uploads\/2024\/01\/og-explora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Explora Sicilia Natura &amp; Sport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/#website\"},\"datePublished\":\"2023-02-07T09:55:21+00:00\",\"dateModified\":\"2024-01-25T15:02:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&nbsp;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/\",\"name\":\"Explora Sicilia Natura &amp; Sport\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.explora-sicilia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Explora Sicilia Natura &amp; Sport","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Privacy Policy - Explora Sicilia Natura &amp; Sport","og_description":"Privacy Policy","og_url":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/","og_site_name":"Explora Sicilia Natura &amp; Sport","article_modified_time":"2024-01-25T15:02:45+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/storage1334.cdn-immedia.net\/wp-content\/uploads\/2024\/01\/og-explora.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/","url":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/","name":"Privacy Policy - Explora Sicilia Natura &amp; Sport","isPartOf":{"@id":"https:\/\/www.explora-sicilia.com\/es\/#website"},"datePublished":"2023-02-07T09:55:21+00:00","dateModified":"2024-01-25T15:02:45+00:00","breadcrumb":{"@id":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.explora-sicilia.com\/es\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.explora-sicilia.com\/es\/"},{"@type":"ListItem","position":2,"name":"&nbsp;"}]},{"@type":"WebSite","@id":"https:\/\/www.explora-sicilia.com\/es\/#website","url":"https:\/\/www.explora-sicilia.com\/es\/","name":"Explora Sicilia Natura &amp; Sport","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.explora-sicilia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/pages\/6617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/comments?post=6617"}],"version-history":[{"count":2,"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/pages\/6617\/revisions"}],"predecessor-version":[{"id":6619,"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/pages\/6617\/revisions\/6619"}],"wp:attachment":[{"href":"https:\/\/www.explora-sicilia.com\/es\/wp-json\/wp\/v2\/media?parent=6617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}